{"id":61,"count":2,"description":"les \u00e9v\u00e8nement de l'ann\u00e9e 2026","link":"https:\/\/assolejourj.fr\/wordpress\/category\/evenements\/2026\/","name":"2026","slug":"2026","taxonomy":"category","parent":31,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des 2026 - Association le Jour J.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/assolejourj.fr\/wordpress\/category\/evenements\/2026\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des 2026 - Association le Jour J.\" \/>\n<meta property=\"og:description\" content=\"les \u00e9v\u00e8nement de l&rsquo;ann\u00e9e 2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/assolejourj.fr\/wordpress\/category\/evenements\/2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Association le Jour J.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@AssoLeJourJ\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/assolejourj.fr\\\/wordpress\\\/category\\\/evenements\\\/2026\\\/\",\"url\":\"https:\\\/\\\/assolejourj.fr\\\/wordpress\\\/category\\\/evenements\\\/2026\\\/\",\"name\":\"Archives des 2026 - Association le Jour J.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/assolejourj.fr\\\/wordpress\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/assolejourj.fr\\\/wordpress\\\/category\\\/evenements\\\/2026\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/assolejourj.fr\\\/wordpress\\\/category\\\/evenements\\\/2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/assolejourj.fr\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les Evenements\",\"item\":\"https:\\\/\\\/assolejourj.fr\\\/wordpress\\\/category\\\/evenements\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/assolejourj.fr\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/assolejourj.fr\\\/wordpress\\\/\",\"name\":\"Association le Jour J\",\"description\":\"Diffuseur de culture rafra\u00eechissante\",\"publisher\":{\"@id\":\"https:\\\/\\\/assolejourj.fr\\\/wordpress\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/assolejourj.fr\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/assolejourj.fr\\\/wordpress\\\/#organization\",\"name\":\"Association le Jour J\",\"url\":\"https:\\\/\\\/assolejourj.fr\\\/wordpress\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/assolejourj.fr\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\/\\/assolejourj.fr\\/wordpress\\/wp-content\\/uploads\\/2023\\/02\\/Logo-1.jpg\",\"contentUrl\":\"https:\\/\\/assolejourj.fr\\/wordpress\\/wp-content\\/uploads\\/2023\\/02\\/Logo-1.jpg\",\"width\":320,\"height\":319,\"caption\":\"Association le Jour J\"},\"image\":{\"@id\":\"https:\\\/\\\/assolejourj.fr\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AssoLeJourJ\\\/?locale=fr_FR\",\"https:\\\/\\\/x.com\\\/AssoLeJourJ\",\"https:\\\/\\\/www.instagram.com\\\/lejourjasso\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des 2026 - Association le Jour J.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/assolejourj.fr\/wordpress\/category\/evenements\/2026\/","og_locale":"fr_FR","og_type":"article","og_title":"Archives des 2026 - Association le Jour J.","og_description":"les \u00e9v\u00e8nement de l&rsquo;ann\u00e9e 2026","og_url":"https:\/\/assolejourj.fr\/wordpress\/category\/evenements\/2026\/","og_site_name":"Association le Jour J.","twitter_card":"summary_large_image","twitter_site":"@AssoLeJourJ","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/assolejourj.fr\/wordpress\/category\/evenements\/2026\/","url":"https:\/\/assolejourj.fr\/wordpress\/category\/evenements\/2026\/","name":"Archives des 2026 - Association le Jour J.","isPartOf":{"@id":"https:\/\/assolejourj.fr\/wordpress\/#website"},"breadcrumb":{"@id":"https:\/\/assolejourj.fr\/wordpress\/category\/evenements\/2026\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/assolejourj.fr\/wordpress\/category\/evenements\/2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/assolejourj.fr\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Les Evenements","item":"https:\/\/assolejourj.fr\/wordpress\/category\/evenements\/"},{"@type":"ListItem","position":3,"name":"2026"}]},{"@type":"WebSite","@id":"https:\/\/assolejourj.fr\/wordpress\/#website","url":"https:\/\/assolejourj.fr\/wordpress\/","name":"Association le Jour J","description":"Diffuseur de culture rafra\u00eechissante","publisher":{"@id":"https:\/\/assolejourj.fr\/wordpress\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/assolejourj.fr\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/assolejourj.fr\/wordpress\/#organization","name":"Association le Jour J","url":"https:\/\/assolejourj.fr\/wordpress\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/assolejourj.fr\/wordpress\/#\/schema\/logo\/image\/","url":"https:\/\/mlwtlfntpdtb.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/assolejourj.fr\/wordpress\/wp-content\/uploads\/2023\/02\/Logo-1.jpg","contentUrl":"https:\/\/mlwtlfntpdtb.i.optimole.com\/w:auto\/h:auto\/q:mauto\/f:best\/https:\/\/assolejourj.fr\/wordpress\/wp-content\/uploads\/2023\/02\/Logo-1.jpg","width":320,"height":319,"caption":"Association le Jour J"},"image":{"@id":"https:\/\/assolejourj.fr\/wordpress\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AssoLeJourJ\/?locale=fr_FR","https:\/\/x.com\/AssoLeJourJ","https:\/\/www.instagram.com\/lejourjasso\/"]}]}},"_links":{"self":[{"href":"https:\/\/assolejourj.fr\/wordpress\/wp-json\/wp\/v2\/categories\/61","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/assolejourj.fr\/wordpress\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/assolejourj.fr\/wordpress\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/assolejourj.fr\/wordpress\/wp-json\/wp\/v2\/categories\/31"}],"wp:post_type":[{"href":"https:\/\/assolejourj.fr\/wordpress\/wp-json\/wp\/v2\/posts?categories=61"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}